{"id":19,"count":2,"description":"","link":"https:\/\/elpasodentist.com\/es\/category\/meet-our-dentist\/","name":"Meet Our Dentist","slug":"meet-our-dentist","taxonomy":"category","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/elpasodentist.com\/es\/category\/meet-our-dentist\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elpasodentist.com\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/19\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elpasodentist.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elpasodentist.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elpasodentist.com\\\/es\\\/category\\\/meet-our-dentist\\\/#listItem\",\"name\":\"Meet Our Dentist\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elpasodentist.com\\\/es\\\/category\\\/meet-our-dentist\\\/#listItem\",\"position\":2,\"name\":\"Meet Our Dentist\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elpasodentist.com\\\/es#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/elpasodentist.com\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/19\\\/#collectionpage\",\"url\":\"https:\\\/\\\/elpasodentist.com\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/19\\\/\",\"name\":\"Meet Our Dentist - El Paso Dentist\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elpasodentist.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elpasodentist.com\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/19\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elpasodentist.com\\\/es\\\/#organization\",\"name\":\"El Paso Dentist\",\"description\":\"Dental Office in East El Paso, TX\",\"url\":\"https:\\\/\\\/elpasodentist.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elpasodentist.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/El_Paso_Dentist_Horizon_City_Dental_Office.png\",\"@id\":\"https:\\\/\\\/elpasodentist.com\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/19\\\/#organizationLogo\",\"width\":350,\"height\":173,\"caption\":\"El Paso Dentist Horizon City Dental Office\"},\"image\":{\"@id\":\"https:\\\/\\\/elpasodentist.com\\\/es\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/19\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elpasodentist.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/elpasodentist.com\\\/es\\\/\",\"name\":\"El Paso Dentist\",\"description\":\"Dental Office in East El Paso, TX\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/elpasodentist.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Meet Our Dentist - El Paso Dentist","description":"","canonical_url":"https:\/\/elpasodentist.com\/es\/category\/meet-our-dentist\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/elpasodentist.com\/es\/wp-json\/wp\/v2\/categories\/19\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/elpasodentist.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/elpasodentist.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/elpasodentist.com\/es\/category\/meet-our-dentist\/#listItem","name":"Meet Our Dentist"}},{"@type":"ListItem","@id":"https:\/\/elpasodentist.com\/es\/category\/meet-our-dentist\/#listItem","position":2,"name":"Meet Our Dentist","previousItem":{"@type":"ListItem","@id":"https:\/\/elpasodentist.com\/es#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/elpasodentist.com\/es\/wp-json\/wp\/v2\/categories\/19\/#collectionpage","url":"https:\/\/elpasodentist.com\/es\/wp-json\/wp\/v2\/categories\/19\/","name":"Meet Our Dentist - El Paso Dentist","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/elpasodentist.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/elpasodentist.com\/es\/wp-json\/wp\/v2\/categories\/19\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/elpasodentist.com\/es\/#organization","name":"El Paso Dentist","description":"Dental Office in East El Paso, TX","url":"https:\/\/elpasodentist.com\/es\/","logo":{"@type":"ImageObject","url":"https:\/\/elpasodentist.com\/wp-content\/uploads\/2026\/05\/El_Paso_Dentist_Horizon_City_Dental_Office.png","@id":"https:\/\/elpasodentist.com\/es\/wp-json\/wp\/v2\/categories\/19\/#organizationLogo","width":350,"height":173,"caption":"El Paso Dentist Horizon City Dental Office"},"image":{"@id":"https:\/\/elpasodentist.com\/es\/wp-json\/wp\/v2\/categories\/19\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/elpasodentist.com\/es\/#website","url":"https:\/\/elpasodentist.com\/es\/","name":"El Paso Dentist","description":"Dental Office in East El Paso, TX","inLanguage":"es-ES","publisher":{"@id":"https:\/\/elpasodentist.com\/es\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/elpasodentist.com\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMeet Our Dentist\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/elpasodentist.com\/es"},{"label":"Meet Our Dentist","link":"https:\/\/elpasodentist.com\/es\/category\/meet-our-dentist\/"}],"_links":{"self":[{"href":"https:\/\/elpasodentist.com\/es\/wp-json\/wp\/v2\/categories\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elpasodentist.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/elpasodentist.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/elpasodentist.com\/es\/wp-json\/wp\/v2\/posts?categories=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}